{"id":5547,"date":"2017-02-10T06:00:19","date_gmt":"2017-02-10T05:00:19","guid":{"rendered":"http:\/\/www.webnauta.it\/wordpress\/?p=5547"},"modified":"2021-10-16T15:54:32","modified_gmt":"2021-10-16T13:54:32","slug":"obiettivi-contro-sistemi","status":"publish","type":"post","link":"https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/","title":{"rendered":"La differenza tra obiettivi e sistemi"},"content":{"rendered":"<p>L&#8217;avrete visto girovagare furtivo tra i commenti, anche se difficilmente lascia tracce del suo passaggio, che tanto <em>&#8220;hanno gi\u00e0 detto tutto (ed il contrario di tutto) gli altri&#8221;<\/em>. Per lo pi\u00f9 preferisce discuterne a quattrocchi, probabilmente perch\u00e9 l&#8217;ipnosi su di me funziona meglio dal vivo. Mister E. \u00e8 il responsabile del Settore Q di webnauta (anch&#8217;io come Bond ho la licenza di uccidere&#8230;i personaggi) e della strategia navale a lungo termine.<br \/>\nLe sue frasi tipiche sono:<br \/>\n<em>&#8220;A che punto sei del libro?&#8221;<\/em> Ahm, ehm, sono un po&#8217; ferma, \u00e8 che mi viene da scrivere pi\u00f9 racconti, e non lo so, ho pure il blog da seguire&#8230;<br \/>\n<em>&#8220;Basta con gli alibi, andiamo oltre. Devi uscire dai soliti schemi.&#8221;<\/em> Eh, ci sarebbe anche quell&#8217;altro progetto&#8230;<br \/>\n<em>&#8220;E&#8217; davvero importante? Definisci quello che vuoi. Davvero.&#8221;<\/em> Quello che voglio io lo so, ma sono continuamente in corsa contro l&#8217;orologio!<br \/>\n<em>&#8220;I grandi lavorano strutturati. Non a vista.&#8221;<\/em> Ottimo direi per me che mi definisco navigatore a vista. Ma del resto, qual \u00e8 il tuo piano in campo?<br \/>\n<em>&#8220;A volte la vera forza della risposta \u00e8 &#8230;non rispondere.&#8221;<\/em> &#8230;&#8230;!<\/p>\n<p>Questo articolo \u00e8 nato una bella mattina in cui mi ha salutato dicendomi: <strong><span style=\"color: #1ea41f;\"><em>&#8220;Vuoi davvero finire quel libro? Ho un link interessante per te!&#8221;<\/em><\/span><\/strong><br \/>\nE credetemi, i suoi link sono davvero al pari delle armi che Q fornisce a Bond: apparentemente insignificanti, terribilmente letali. Delle bombe mentali mica da poco, che ti rodono dentro per settimane. Ma che ti fanno uscire da quella che viene detta comfort-zone. E scattare in avanti alla potenza del motore v8 della <a href=\"http:\/\/www.astonmartin.com\/en\/cars\/db10\" target=\"_blank\" rel=\"noopener\">Aston Martin DB10<\/a>.<\/p>\n<p>Di che si tratta stavolta? <span style=\"color: #1ea41f;\"><strong>Dimenticarsi degli obiettivi e concentrarsi invece sui sistemi.<\/strong><\/span><br \/>\nSemplice, no?<\/p>\n<p><!--more--><\/p>\n<h2><\/h2>\n<h2><span style=\"color: #1ea41f;\">La differenza tra obiettivi e sistemi<\/span><\/h2>\n<p>Tutti noi desideriamo ottenere qualcosa nella vita, che sia raggiungere la forma fisica perfetta, acquistare la villa dei nostri sogni, creare un&#8217;azienda solida e fiorente, cambiare la vecchia auto con una fuoriserie di tutto rispetto, vincere un premio ambito. Nella fattispecie, pubblicare un libro, meglio se un bestseller internazionale. No, non vi sforzate di negare, sotto sotto nessuno ci sputerebbe sopra.<\/p>\n<p>Per come ci hanno sempre insegnato, anche a scuola, <strong><span style=\"color: #1ea41f;\">la maniera per conseguire qualcosa \u00e8 fissare un obiettivo specifico<\/span><span style=\"color: #1ea41f;\">:<\/span><\/strong> se vogliamo arrivare preparati al compito in classe di fine mese, dobbiamo imparare gli argomenti stabiliti dall&#8217;insegnante; se vogliamo dimagrire dobbiamo diminuire la quantit\u00e0 di calorie ingerite e contemporaneamente aumentare l&#8217;attivit\u00e0 fisica, finch\u00e9 non rientreremo nella taglia inferiore; se vogliamo cambiare casa o automobile dovremmo iniziare a risparmiare e\/o lavorare di pi\u00f9 per accantonare il denaro necessario alla compravendita. Se davvero vogliamo finire nella classifica dei libri pi\u00f9 venduti, dobbiamo scrivere quel libro e impegnarci per trovargli una casa editrice.<\/p>\n<p>Siamo sicuri che questo sia il modo di procedere corretto? Secondo <a href=\"http:\/\/jamesclear.com\/?utm_source=pocket\" target=\"_blank\" rel=\"noopener\"><strong>James Clear<\/strong><\/a>\u00a0no, c&#8217;\u00e8 un metodo migliore per conquistare i nostri trofei e si riduce alla <strong><span style=\"color: #1ea41f;\">differenza tra obiettivi (goals) e sistemi (systems).<\/span><\/strong> Cercher\u00f2 di tradurvi, e in parte spiegarvi, questo suo articolo: <a href=\"https:\/\/jamesclear.com\/goals-systems\" target=\"_blank\" rel=\"noopener\"><em>Forget About Setting Goals. Focus on This Instead.<\/em><\/a><\/p>\n<p>Riprendiamo gli esempi che ho citato sopra:<\/p>\n<ul>\n<li>per lo studente, l&#8217;obiettivo \u00e8 ottenere un voto alto, il sistema \u00e8 seguire e studiare ogni giorno le lezioni del professore;<\/li>\n<li>per un atleta, l&#8217;obiettivo \u00e8 vincere una maratona, il sistema \u00e8 il programma di allenamento e nutrizione per i prossimi mesi;<\/li>\n<li>per un imprenditore, l&#8217;obiettivo \u00e8 raggiungere un fatturato di un milione di euro, il sistema sono i processi di marketing e vendita;<\/li>\n<li>per uno scrittore, l&#8217;obiettivo \u00e8 quello di scrivere un libro, il sistema \u00e8 la routine di scrittura di ogni settimana.<\/li>\n<\/ul>\n<p><strong><span style=\"color: #1ea41f;\">Ma se ignoriamo completamente i nostri obiettivi e ci concentriamo esclusivamente sul sistema, avremmo lo stesso risultato?<\/span><\/strong><br \/>\nJames Clear pensa di si e come dimostrazione prende in considerazione proprio quanto ottenuto dal suo blog in un anno.<br \/>\nProviamo a modificare il suo esempio considerando i numeri di webnauta: nel 2016 ho scritto 60 articoli e, per una media di 1.800 parole (alcune volte di meno, spesso con i racconti, di pi\u00f9), fanno la bellezza di 108.000 parole. Considerando che un romanzo contemporaneo oscilla tra le 50.000 e le 60.000 parole (pur con le eccezioni, come<em> Il gioco del trono<\/em> di George R.R. Martin con 298.000 parole),<strong><span style=\"color: #1ea41f;\"> avrei scritto quasi due libri pieni.<\/span><\/strong><br \/>\nImpressionante vero?<br \/>\nVerrebbe da chiedersi se \u00e8 davvero necessario avere un blog per scrivere un libro, ma ad essere onesti senza il blog non avrei probabilmente scritto nemmeno mezza parola. L&#8217;appetito vien mangiando.<\/p>\n<p>Eppure per il blog non mi sono mai posta un obiettivo definito di parole, n\u00e9 in relazione all&#8217;anno n\u00e9 per ogni singolo articolo. Semplicemente quando ho aperto webnauta ho deciso, all&#8217;inizio a malincuore, di rispettare l&#8217;impegno di un solo post a settimana, in giorno variabile. L&#8217;idea era di pubblicare il mercoled\u00ec, poi le urgenze lavorative me l&#8217;hanno fatto spostare al gioved\u00ec, ma come vedete spesso si arriva al venerd\u00ec, con buona pace della SEO per cui il venerd\u00ec non \u00e8 una giornata proficua (eppure i miei lettori mi leggono anche il sabato e la domenica, forse dipende dagli argomenti?).<\/p>\n<p>Qualche volta \u00e8 andata bene e gli articoli si scrivevano da soli senza fatica, qualche volta sono arrivata cocciutamente alle ore piccole, beccandomi sia i refusi nascosti in ogni angolo che le ramanzine del mio ufficiale di rotta Simona preoccupata per il mio stato di salute. <em>Don&#8217;t worry. I&#8217;m a <a href=\"http:\/\/www.mpc2017.com\/pages\/mpc\" target=\"_blank\" rel=\"noopener\">Peaker<\/a>, I&#8217;m strong enough.<\/em> \ud83d\ude09<\/p>\n<p>Di sicuro<strong><span style=\"color: #1ea41f;\"> non ho mai settato un obiettivo in termini di parole<\/span><\/strong>, e in realt\u00e0 nemmeno di pubblicazione: sapevo benissimo che non sarebbe morto nessuno se una settimana avessi saltato di concludere il mio post. Non ho mai seguito le regole SEO che vedono un numero di parole minimo per un buon piazzamento. E certo non ho mai pensato: &#8220;Voglio scrivere due libri quest&#8217;anno!&#8221;<\/p>\n<p>Mi sono semplicemente concentrata nella scrittura di un solo articolo a settimana, giorno per giorno, calmierando la mia ansia con un piano di lavoro concreto (il cosiddetto calendario editoriale). Mi sono focalizzata sul sistema e sul processo. E dopo 12 mesi il risultato \u00e8 stato di 108.000 parole, nonch\u00e9 un buon piazzamento di visualizzazioni.<\/p>\n<p>James Clear \u00a0ha individuato tre motivi principali per cui si dovrebbe prestare attenzione ai sistemi piuttosto che agli obiettivi.<\/p>\n<p>&nbsp;<\/p>\n<h2><span style=\"color: #1ea41f;\">1. Gli Obiettivi riducono la vostra felicit\u00e0 presente.<\/span><\/h2>\n<p>Quando si lavora puntando ad un obiettivo, continuiamo a dirci di non essere ancora soddisfatti, ma che lo saremo quando l&#8217;avremo raggiunto. Il problema di questa mentalit\u00e0 \u00e8 che stiamo mettendo fuori dalla nostra portata la felicit\u00e0 e il successo, fino al prossimo obiettivo. Saremo felici quando l&#8217;avremo conseguito. Ma adesso? Non possiamo pi\u00f9 essere felici ora?<\/p>\n<p>Se avessi deciso di scrivere due libri in un anno, mi sarei bloccata al solo pensiero (anzi, ne basta gi\u00e0 uno solo di libro da scrivere, no?). Perch\u00e9 <strong><span style=\"color: #1ea41f;\">fissare un obiettivo \u00e8 stressante<\/span><\/strong>, in maniera esponenziale a quanto lo riteniamo difficile da conseguire. E siamo abituati a farlo tutto il tempo, per tutte le cose della nostra vita, dalla dieta, al lavoro, alla scrittura. Se ci si concentra sulla pratica invece che sulle prestazioni, si pu\u00f2 godere il momento presente e migliorare allo stesso tempo.<\/p>\n<p><em><strong><span style=\"color: #1ea41f;\">Soluzione: Impegnarsi per un processo continuo, non per un singolo obiettivo.<\/span><\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<h2><span style=\"color: #1ea41f;\">2. Gli Obiettivi contrastano con i progressi a lungo termine.<\/span><\/h2>\n<p>Si potrebbe pensare che il vostro obiettivo vi terr\u00e0 motivati \u200b\u200bnel lungo termine, ma questo non \u00e8 sempre vero. Per quanto riguarda la scrittura,<em> <a href=\"http:\/\/www.webnauta.it\/wordpress\/on-writing-stephen-king\/\" target=\"_blank\" rel=\"noopener\">Stephen King<\/a><\/em>\u00a0sostiene che la prima bozza di un romanzo deve essere scritta in non pi\u00f9 di tre mesi, altrimenti si perde interesse per la storia e questa non sar\u00e0 mai terminata.<\/p>\n<p>Consideriamo chi deve perdere drasticamente peso per migliorare la propria salute. Molte persone lavorano duramente per mesi, sia per l&#8217;applicazione di una dieta restrittiva sia come esercizio fisico quotidiano. Ma non appena avranno eliminato i chili in eccesso ed ottenuta la forma fisica consigliata, smetteranno di mangiare sano e di continuare l&#8217;attivit\u00e0 motoria. Questo perch\u00e9<strong><span style=\"color: #1ea41f;\"> l&#8217;obiettivo \u00e8 raggiunto e non \u00e8 pi\u00f9 l\u00ec a motivarli costantemente.<\/span><\/strong> E&#8217; proprio questo che innesca l&#8217;effetto &#8220;yo-yo&#8221; nelle diete, con cicli continui di perdita e riacquisto di peso, senza sviluppare un progresso a lungo termine ed un risultato pressoch\u00e9 definitivo.<\/p>\n<p>E qui James Clear cita un esempio personale che calza bene anche alla sottoscritta, pari pari: parliamo di allenarsi in palestra. Qualsiasi sia il vostro allenamento, da lezioni in gruppo a set di esercizi personali da completare in sala macchine, capita il giorno storto in cui non riuscite a terminare la lezione nemmeno passando al basso impatto (meno attivit\u00e0 cardio eliminando salti e diminuendo il carico degli attrezzi) o che non concludete la serie di ripetizioni a causa di uno stiramento dovuto alla stanchezza. In una situazione del genere, una mentalit\u00e0 per obiettivi vi costringerebbe a terminare comunque l&#8217;allenamento (rischiando un danno peggiore), perch\u00e9 se non si arriva all&#8217;obiettivo ci si sente falliti. Chi invece si concentra sui sistemi, non ha problemi a smettere per quel giorno, perch\u00e9 sa benissimo che si tratta solo di un giorno e non intaccher\u00e0 in nessun modo il processo di tutti gli altri allenamenti, che potranno riprendere il giorno successivo. Ed \u00e8 cos\u00ec: la costanza in palestra premia di pi\u00f9.<\/p>\n<p>Per questo i sistemi sono pi\u00f9 preziosi degli obiettivi: gli obiettivi sono per il risultato a breve termine; i sistemi riguardano il processo a lungo termine. Alla fine, il processo vince sempre.<\/p>\n<p><em><strong><span style=\"color: #1ea41f;\">Soluzione: Dimenticate il bisogno di risultati immediati.<\/span><\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<h2><span style=\"color: #1ea41f;\">\u00a03. Gli Obiettivi fingono di dare il controllo su cose che non sono controllabili.<\/span><\/h2>\n<p>Non possiamo predire il futuro, eppure ogni volta che fissiamo un obiettivo cerchiamo di pianificare come e quando lo raggiungeremo, di prevedere quanto velocemente possiamo progredire in quella direzione. Ma non consideriamo circostanze o impedimenti che potrebbero presentarsi lungo il percorso, non possiamo prevederli.<\/p>\n<p>Pensiamo all&#8217;attivit\u00e0 di blogging: come lo stesso James Clear, anch&#8217;io verifico ogni settimana l&#8217;andamento delle visite al sito, globali e per l&#8217;ultimo articolo pubblicato. Ci sono post che funzionano meglio di altri, argomenti che attirano lettori pi\u00f9 facilmente di altri, diverse modalit\u00e0 di farli viaggiare all&#8217;interno dei social media o di categorizzarli sui motori di ricerca, ottenendo letture focalizzate. Vanno anche considerate le stagionalit\u00e0 di determinati contenuti o dei comportamenti dei lettori. Man mano che il blog procede, decidiamo come aggiustare il calendario editoriale in base alle esigenze personali e ai feedback ottenuti finora.<br \/>\nCi si dimentica di predire il futuro, tanto non \u00e8 possibile, e si costruisce un sistema in grado di segnalare quando effettuare degli aggiustamenti,<strong><span style=\"color: #1ea41f;\"> senza subire lo stress di un obiettivo fisso e irremovibile.<\/span><\/strong><\/p>\n<p>Che \u00e8 il concetto di navigare a vista, fondamentalmente! \ud83d\ude09<\/p>\n<p><em><strong><span style=\"color: #1ea41f;\">Soluzione: Costruire un ciclo di verifica dei risultati.<\/span><\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<h2><span style=\"color: #1ea41f;\">Focalizzarsi sui Sistemi<\/span><\/h2>\n<p>Alla conclusione del suo articolo, James Clear chiarisce: gli obiettivi non sono inutili, sono buoni per pianificare i progressi ma i sistemi sono migliori per progredire davvero. Gli obiettivi possono fornire la direzione e persino spingere in avanti nel breve termine, ma alla fine <strong><span style=\"color: #1ea41f;\">un sistema ben progettato sar\u00e0 sempre vincente.<\/span><\/strong> Avere un sistema \u00e8 ci\u00f2 che conta, affidarsi al processo \u00e8 ci\u00f2 che fa la differenza.<\/p>\n<p>Non so voi, ma questo articolo, cos\u00ec semplice, e magari anche un po&#8217; banale, mi ha aperto ad un mondo di considerazioni. Perch\u00e9 non sono concetti puramente teorici: la dimostrazione che l&#8217;ho gi\u00e0 fatto \u00e8 sotto i vostri occhi. Ora devo solo capire come, oltre al blog, far rientrare nel mio processo quotidiano anche quel libro da scrivere.<br \/>\nQualsiasi sia il vostro obiettivo attuale, cosa vi impedisce di trasformarlo in un sistema continuo?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;avrete visto girovagare furtivo tra i commenti, anche se difficilmente lascia tracce del suo passaggio, che tanto &#8220;hanno gi\u00e0 detto tutto (ed il contrario di tutto) gli altri&#8221;. Per lo pi\u00f9 preferisce discuterne a quattrocchi, probabilmente perch\u00e9 l&#8217;ipnosi su di me funziona meglio dal vivo. Mister E. \u00e8 il responsabile del Settore Q di webnauta [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5546,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[34,23,25],"class_list":["post-5547","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-risorse-per-scribacchini","tag-ispirazioni","tag-scrittura","tag-tecniche"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.8 (Yoast SEO v26.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La differenza tra obiettivi e sistemi - webnauta<\/title>\n<meta name=\"description\" content=\"Dimenticarsi degli obiettivi e concentrarsi invece sui sistemi? Si pu\u00f2, per raggiungere risultati duraturi...webnauta - navigatore in un oceano di parole\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La differenza tra obiettivi e sistemi\" \/>\n<meta property=\"og:description\" content=\"Dimenticarsi degli obiettivi e concentrarsi invece sui sistemi? Si pu\u00f2, per raggiungere risultati duraturi...webnauta - navigatore in un oceano di parole\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/\" \/>\n<meta property=\"og:site_name\" content=\"webnauta\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/barbara.businaro.9\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/barbara.businaro.9\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-10T05:00:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-16T13:54:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.webnauta.it\/wordpress\/wp-content\/uploads\/2017\/02\/Goals_vs_Systems.png\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Barbara Businaro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@barbarawebnauta\" \/>\n<meta name=\"twitter:site\" content=\"@barbarawebnauta\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Barbara Businaro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/\"},\"author\":{\"name\":\"Barbara Businaro\",\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/#\/schema\/person\/9a1f7a6e3b52bbe5b9d265d2d671d1a1\"},\"headline\":\"La differenza tra obiettivi e sistemi\",\"datePublished\":\"2017-02-10T05:00:19+00:00\",\"dateModified\":\"2021-10-16T13:54:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/\"},\"wordCount\":1903,\"commentCount\":23,\"publisher\":{\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/#\/schema\/person\/9a1f7a6e3b52bbe5b9d265d2d671d1a1\"},\"image\":{\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.webnauta.it\/wordpress\/wp-content\/uploads\/2017\/02\/Goals_vs_Systems.png\",\"keywords\":[\"ispirazioni\",\"scrittura\",\"tecniche\"],\"articleSection\":[\"Risorse per scribacchini\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/\",\"url\":\"https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/\",\"name\":\"La differenza tra obiettivi e sistemi - webnauta\",\"isPartOf\":{\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.webnauta.it\/wordpress\/wp-content\/uploads\/2017\/02\/Goals_vs_Systems.png\",\"datePublished\":\"2017-02-10T05:00:19+00:00\",\"dateModified\":\"2021-10-16T13:54:32+00:00\",\"description\":\"Dimenticarsi degli obiettivi e concentrarsi invece sui sistemi? Si pu\u00f2, per raggiungere risultati duraturi...webnauta - navigatore in un oceano di parole\",\"breadcrumb\":{\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/#primaryimage\",\"url\":\"https:\/\/www.webnauta.it\/wordpress\/wp-content\/uploads\/2017\/02\/Goals_vs_Systems.png\",\"contentUrl\":\"https:\/\/www.webnauta.it\/wordpress\/wp-content\/uploads\/2017\/02\/Goals_vs_Systems.png\",\"width\":640,\"height\":427,\"caption\":\"Goals vs Systems - Obiettivi contro sistemi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.webnauta.it\/wordpress\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La differenza tra obiettivi e sistemi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/#website\",\"url\":\"https:\/\/www.webnauta.it\/wordpress\/\",\"name\":\"webnauta\",\"description\":\"navigatore in un oceano di parole\",\"publisher\":{\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/#\/schema\/person\/9a1f7a6e3b52bbe5b9d265d2d671d1a1\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.webnauta.it\/wordpress\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/#\/schema\/person\/9a1f7a6e3b52bbe5b9d265d2d671d1a1\",\"name\":\"Barbara Businaro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.webnauta.it\/wordpress\/wp-content\/uploads\/2020\/02\/BarbaraBusinaro2020_rounded.png\",\"contentUrl\":\"https:\/\/www.webnauta.it\/wordpress\/wp-content\/uploads\/2020\/02\/BarbaraBusinaro2020_rounded.png\",\"width\":500,\"height\":512,\"caption\":\"Barbara Businaro\"},\"logo\":{\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/#\/schema\/person\/image\/\"},\"description\":\"webnauta.it \u2022 Blog personale di Barbara Businaro \u2022 Scrivo, tra una tempesta e l''altra. Chiunque pu\u00f2 tenere il timone quando il mare \u00e8 calmo.\",\"sameAs\":[\"http:\/\/www.webnauta.it\",\"http:\/\/www.facebook.com\/barbara.businaro.9\",\"https:\/\/www.instagram.com\/barbarawebnauta\/\",\"https:\/\/x.com\/barbarawebnauta\"],\"url\":\"https:\/\/www.webnauta.it\/wordpress\/author\/maxadmin\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La differenza tra obiettivi e sistemi - webnauta","description":"Dimenticarsi degli obiettivi e concentrarsi invece sui sistemi? Si pu\u00f2, per raggiungere risultati duraturi...webnauta - navigatore in un oceano di parole","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/","og_locale":"it_IT","og_type":"article","og_title":"La differenza tra obiettivi e sistemi","og_description":"Dimenticarsi degli obiettivi e concentrarsi invece sui sistemi? Si pu\u00f2, per raggiungere risultati duraturi...webnauta - navigatore in un oceano di parole","og_url":"https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/","og_site_name":"webnauta","article_publisher":"http:\/\/www.facebook.com\/barbara.businaro.9","article_author":"http:\/\/www.facebook.com\/barbara.businaro.9","article_published_time":"2017-02-10T05:00:19+00:00","article_modified_time":"2021-10-16T13:54:32+00:00","og_image":[{"width":640,"height":427,"url":"https:\/\/www.webnauta.it\/wordpress\/wp-content\/uploads\/2017\/02\/Goals_vs_Systems.png","type":"image\/png"}],"author":"Barbara Businaro","twitter_card":"summary_large_image","twitter_creator":"@barbarawebnauta","twitter_site":"@barbarawebnauta","twitter_misc":{"Scritto da":"Barbara Businaro","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/#article","isPartOf":{"@id":"https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/"},"author":{"name":"Barbara Businaro","@id":"https:\/\/www.webnauta.it\/wordpress\/#\/schema\/person\/9a1f7a6e3b52bbe5b9d265d2d671d1a1"},"headline":"La differenza tra obiettivi e sistemi","datePublished":"2017-02-10T05:00:19+00:00","dateModified":"2021-10-16T13:54:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/"},"wordCount":1903,"commentCount":23,"publisher":{"@id":"https:\/\/www.webnauta.it\/wordpress\/#\/schema\/person\/9a1f7a6e3b52bbe5b9d265d2d671d1a1"},"image":{"@id":"https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webnauta.it\/wordpress\/wp-content\/uploads\/2017\/02\/Goals_vs_Systems.png","keywords":["ispirazioni","scrittura","tecniche"],"articleSection":["Risorse per scribacchini"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/","url":"https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/","name":"La differenza tra obiettivi e sistemi - webnauta","isPartOf":{"@id":"https:\/\/www.webnauta.it\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/#primaryimage"},"image":{"@id":"https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webnauta.it\/wordpress\/wp-content\/uploads\/2017\/02\/Goals_vs_Systems.png","datePublished":"2017-02-10T05:00:19+00:00","dateModified":"2021-10-16T13:54:32+00:00","description":"Dimenticarsi degli obiettivi e concentrarsi invece sui sistemi? Si pu\u00f2, per raggiungere risultati duraturi...webnauta - navigatore in un oceano di parole","breadcrumb":{"@id":"https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/#primaryimage","url":"https:\/\/www.webnauta.it\/wordpress\/wp-content\/uploads\/2017\/02\/Goals_vs_Systems.png","contentUrl":"https:\/\/www.webnauta.it\/wordpress\/wp-content\/uploads\/2017\/02\/Goals_vs_Systems.png","width":640,"height":427,"caption":"Goals vs Systems - Obiettivi contro sistemi"},{"@type":"BreadcrumbList","@id":"https:\/\/www.webnauta.it\/wordpress\/obiettivi-contro-sistemi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.webnauta.it\/wordpress\/"},{"@type":"ListItem","position":2,"name":"La differenza tra obiettivi e sistemi"}]},{"@type":"WebSite","@id":"https:\/\/www.webnauta.it\/wordpress\/#website","url":"https:\/\/www.webnauta.it\/wordpress\/","name":"webnauta","description":"navigatore in un oceano di parole","publisher":{"@id":"https:\/\/www.webnauta.it\/wordpress\/#\/schema\/person\/9a1f7a6e3b52bbe5b9d265d2d671d1a1"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.webnauta.it\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Person","Organization"],"@id":"https:\/\/www.webnauta.it\/wordpress\/#\/schema\/person\/9a1f7a6e3b52bbe5b9d265d2d671d1a1","name":"Barbara Businaro","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.webnauta.it\/wordpress\/#\/schema\/person\/image\/","url":"https:\/\/www.webnauta.it\/wordpress\/wp-content\/uploads\/2020\/02\/BarbaraBusinaro2020_rounded.png","contentUrl":"https:\/\/www.webnauta.it\/wordpress\/wp-content\/uploads\/2020\/02\/BarbaraBusinaro2020_rounded.png","width":500,"height":512,"caption":"Barbara Businaro"},"logo":{"@id":"https:\/\/www.webnauta.it\/wordpress\/#\/schema\/person\/image\/"},"description":"webnauta.it \u2022 Blog personale di Barbara Businaro \u2022 Scrivo, tra una tempesta e l''altra. Chiunque pu\u00f2 tenere il timone quando il mare \u00e8 calmo.","sameAs":["http:\/\/www.webnauta.it","http:\/\/www.facebook.com\/barbara.businaro.9","https:\/\/www.instagram.com\/barbarawebnauta\/","https:\/\/x.com\/barbarawebnauta"],"url":"https:\/\/www.webnauta.it\/wordpress\/author\/maxadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.webnauta.it\/wordpress\/wp-json\/wp\/v2\/posts\/5547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.webnauta.it\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.webnauta.it\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.webnauta.it\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.webnauta.it\/wordpress\/wp-json\/wp\/v2\/comments?post=5547"}],"version-history":[{"count":2,"href":"https:\/\/www.webnauta.it\/wordpress\/wp-json\/wp\/v2\/posts\/5547\/revisions"}],"predecessor-version":[{"id":25881,"href":"https:\/\/www.webnauta.it\/wordpress\/wp-json\/wp\/v2\/posts\/5547\/revisions\/25881"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.webnauta.it\/wordpress\/wp-json\/wp\/v2\/media\/5546"}],"wp:attachment":[{"href":"https:\/\/www.webnauta.it\/wordpress\/wp-json\/wp\/v2\/media?parent=5547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.webnauta.it\/wordpress\/wp-json\/wp\/v2\/categories?post=5547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.webnauta.it\/wordpress\/wp-json\/wp\/v2\/tags?post=5547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}