{"id":27255,"date":"2022-06-30T22:30:07","date_gmt":"2022-06-30T20:30:07","guid":{"rendered":"https:\/\/www.webnauta.it\/wordpress\/?p=27255"},"modified":"2022-06-30T20:14:33","modified_gmt":"2022-06-30T18:14:33","slug":"come-si-scelgono-i-libri-estivi","status":"publish","type":"post","link":"https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/","title":{"rendered":"Come si scelgono i libri estivi?"},"content":{"rendered":"<p>Nonostante le temperature torride che gi\u00e0 da due mesi ci affliggono e che di fatto ci hanno catapultato in questa estate infuocata senza nemmeno un briciolo di primavera, ho cominciato a sentire l&#8217;atmosfera estiva solo in questa settimana. Le valigie per le vacanze sono in fase di preparazione, per ora il loro ipotetico contenuto sparso in mucchietti in giro per casa, e lo zainetto dei libri da portare in villeggiatura mi guarda da un angolo del divano. E&#8217; ancora tristemente vuoto e devo decidermi con quali titoli riempirlo. Un bel dilemma. Gi\u00e0 sono affetta da <a href=\"https:\/\/www.webnauta.it\/wordpress\/libri-non-letti-tsundoku\/\" target=\"_blank\" rel=\"noopener\"><em>Tsundoku<\/em><\/a>\u00a0e accumulo traballanti pile di libri sul comodino che ciclicamente oscurano la lampada con cui dovrei leggerli, quei libri. Ma sono pure un lettore fortemente emotivo, mi lascio condizionare dall&#8217;ambiente e dalla disposizione d&#8217;animo del momento, e quello che potrei scegliere adesso, tra le silenziose mura casalinghe, potrebbe essere totalmente sbagliato una volta arrivata a destinazione, col mare blu fuori dalla porta e il profumo della salsedine che mi inebria i sensi.<\/p>\n<p><span style=\"color: #3366ff;\"><strong>In genere mi preparo una lista sommaria, all&#8217;inizio solo mentale<\/strong><\/span>, poi diventa un altro mucchietto vicino allo zaino, di quello che vorrei leggere in vacanza, tra un bagno e l&#8217;altro, un&#8217;escursione o una camminata, o nella quiete del dopo cena, ascoltando lo sciabordio della risacca. Di solito cerco di portarmi appresso almeno tre volumi, differenti per genere letterario e complessit\u00e0, ma niente di troppo intricato per le meningi, solo narrativa di consumo, magari anche qualche romanzo classico, che i capolavori della letteratura sono come il tubino nero, non passano mai di moda e si accordano per ogni occasione, ma comunque qualcosa di rilassante. L&#8217;elenco prevede pure qualche titolo per il rientro, per cercare di prolungare il pi\u00f9 possibile, magari fino a settembre inoltrato, i benefici della pausa vacanziera, l&#8217;illusione di essere ancora in ferie con qualche ora di lavoro nel mezzo. \ud83d\ude1b<\/p>\n<p>Sto ancora leggendo l&#8217;immenso <a href=\"https:\/\/www.amazon.it\/Guerra-pace-Lev-Tolstoj\/dp\/8817117382\" target=\"_blank\" rel=\"noopener\"><em>Guerra e pace<\/em><\/a>\u00a0di Lev Tolstoj, dove l&#8217;immensit\u00e0 non \u00e8 una questione di dimensioni dell&#8217;oggetto libro quanto della storia in esso raccontata. Qualche anno fa qualcuno mi disse che Guerra e pace \u00e8 IL libro per eccellenza e se non hai letto quello, non hai letto veramente niente. Sono corsa in libreria ad acquistarlo il giorno in cui \u00e8 scoppiata quella guerra, ai primi di marzo, che ancora si trascina laggi\u00f9 ad est, tra terribili scontri e atroci sofferenze. Ho affidato a Tolstoj l&#8217;arduo compito di spiegarmi perch\u00e9 gli uomini sentono il bisogno della guerra. Sono all&#8217;ultimo quarto del romanzo, le pagine avanti a me iniziano a diminuire tristemente, non posso affermare di aver trovato una risposta alle mie domande, sono capitoli che necessitano di profonda riflessione. Anche per questo lo leggo con ponderata lentezza. E sono tentata di portarlo con me, perch\u00e9 staccarmene e sospendere la lettura proprio adesso sar\u00e0 davvero difficile, ma la decisione \u00e8 stupidamente pratica: ho scelto un&#8217;edizione in brochure che non resisterebbe al viaggio, gi\u00e0 ho dovuto incollare le prime ed ultime pagine che si stavano staccando dal volume. Dovr\u00e0 attendermi qui, al ritorno.<\/p>\n<p>Cos\u00ec mentre stavo adocchiando le pile sul comodino e i ripiani della libreria per capire quali altri romanzi non ancora letti portare in ferie con me, trovo <span style=\"color: #3366ff;\"><strong>un altro articolo interessante nella newsletter Voices<\/strong><\/span> curata da <a href=\"https:\/\/it.wikipedia.org\/wiki\/Annalisa_Monfreda\" target=\"_blank\" rel=\"noopener\"><em>Annalisa Monfreda<\/em><\/a>, giornalista impegnata attivamente sul tema della disparit\u00e0 di genere sul mondo del lavoro, ex direttrice di riviste nazionali come Top Girl, Geo Italia, Cosmopolitan e Donna Moderna. L&#8217;ho conosciuta proprio tramite questa sua lettera aperta sulla scelta, ponderata e non meno sofferta, di concludere l&#8217;esperienza con Donna Moderna: <em><a href=\"https:\/\/a-monfreda.medium.com\/breve-storia-delle-mie-dimissioni-a757b5b30c6c\" target=\"_blank\" rel=\"noopener\">Breve storia delle mie dimissioni<\/a>.<\/em> Questa sua cronistoria capit\u00f2 nella mia bacheca al momento giusto, quello in cui pure io stavo cambiando lavoro, settore e decisamente anche vita. Cos\u00ec mi sono iscritta alla sua newsletter, certa dell&#8217;occasione di imparare qualcosa di nuovo.<\/p>\n<p>Ecco che, in uno degli ultimi invii, si parla proprio di <span style=\"color: #3366ff;\"><strong>come si scelgono i libri estivi<\/strong><\/span> e il riferimento \u00e8 a questo post del consulente e blogger americano Wally Bock: <a href=\"https:\/\/us8.campaign-archive.com\/?e=4c4e43e2b4&amp;id=954a2ced14&amp;u=c34f3f87b741491c89c296eea\" target=\"_blank\" rel=\"noopener\"><em>Time to Make Your Summer Reading List for 2022<\/em><\/a> (trad. Tempo di stilare la lista di lettura estiva per il 2022). Il padre infatti era un grandissimo lettore, al ritmo di due o tre libri alla settimana gi\u00e0 durante il periodo lavorativo. Ma l&#8217;estate per lui era il momento di leggere cose differenti, potendo approfittare di un intero mese di ferie (beato lui!!) E aveva perfezionato un modo particolare per scegliere i suoi libri estivi, <span style=\"color: #3366ff;\"><strong>suddividendoli in tre liste da cui attingere per la scelta finale<\/strong><\/span>, prima della partenza per la villeggiatura. Beh, era sicuramente un&#8217;altra epoca dove non esistevano gli ereader e la possibilit\u00e0 di scaricare al volo un romanzo in formato elettronico, in assenza di librerie fisiche dove acquistare un libro di ripiego. Tra l&#8217;altro, porter\u00f2 con me il mio fedele Kobo, ma l&#8217;elettronica e l&#8217;acqua, specie salata, non vanno molto d&#8217;accordo e quindi preferisco, una volta di pi\u00f9, leggere in edizione cartacea. Il profumo della carta e quello del mare, cosa vuoi di pi\u00f9?! \ud83d\ude00<\/p>\n<p>Probabilmente ho anche aspettative elevate sulla lettura d&#8217;estate, perch\u00e9 alla fine non ho tutto questo tempo libero che il mio cervello immagina di avere a disposizione. Anche quando sono in vacanza, mi lascio prendere dalla frenesia di vedere tutto, natura e cultura, e provare tutto, tuffi e trekking. Cos\u00ec che la lettura rischia di essere relegata alla pausa dell&#8217;asciugatura del costume o alla ripresa del fiato, prima della salita successiva. Penso per\u00f2 che questo metodo possa darmi uno spunto in pi\u00f9. Per scegliere bene e ottimizzare relax e divertimento.<\/p>\n<p><!--more--><\/p>\n<h2><span style=\"color: #3366ff;\">Prepara una lista e poi scegli i migliori<\/span><\/h2>\n<p><span style=\"color: #3366ff;\"><strong>Wally Bock, classe 1946, consulente aziendale su formazione e leadership<\/strong><\/span> con la sua societ\u00e0 <a href=\"https:\/\/www.threestarleadership.com\/\" target=\"_blank\" rel=\"noopener\"><em>Three Star Leadership<\/em><\/a>, \u00e8 anche autore di saggistica sulle stesse tematiche, blogger, ghostwriter e coach di scrittura per il business. Aiuta le persone a scrivere le loro idee in modo da farle diventare un libro da pubblicare, nel suo sito <a href=\"https:\/\/writingabookwithwally.com\" target=\"_blank\" rel=\"noopener\"><em>Wally Bock&#8217;s writing edge<\/em><\/a>. Interessante tra i numerosi post del suo blog, ancora oggi molto attivo, questo suo articolo su Cosa fare in un giorno in cui non si ha voglia di scrivere: <a href=\"https:\/\/writingabookwithwally.com\/writing-a-book\/what-to-do-on-a-day-when-you-dont-feel-like-writing\" target=\"_blank\" rel=\"noopener\"><em>What to Do on a Day When You Don\u2019t Feel Like Writing<\/em><\/a><br \/>\nTra l&#8217;altro, negli anni &#8217;80 scriveva nei gruppi di discussione online su CompuServe, gli stessi forum dove Diana Gabaldon condivideva la stesura del suo primo romanzo <a href=\"https:\/\/www.webnauta.it\/wordpress\/tag\/outlander\/\" target=\"_blank\" rel=\"noopener\"><em>Outlander<\/em><\/a>\u00a0nella sezione Books and Writers Community. Sorrido per questo ennesimo collegamento. \ud83d\ude42<\/p>\n<p>Come spiega nell&#8217;articolo originale, \u00e8 il Memorial Day (l&#8217;ultimo luned\u00ec di maggio, festa nazionale negli gli Stati Uniti, dove onorano i loro caduti in tutte le guerre) il giorno in cui Wally Bock sente cominciare l&#8217;estate nel suo calendario psicologico e decide le letture che lo accompagneranno per quella stagione. Il metodo che utilizza per scegliere i suoi libri gli \u00e8 stato tramandato in famiglia, con qualche personale aggiunta.<br \/>\nIl padre era infatti un pastore luterano e la vita di un uomo di chiesta \u00e8 molto intensa, piena di preparazione di sermoni, visite ai membri della congregazione e riunioni di ogni tipo. Era soprattutto un lettore vorace e, nonostante i suoi impegni, di solito leggeva due o tre libri alla settimana. Alcune letture erano legate al suo lavoro di pastore, ma amava anche la Storia e le biografie. Mentre le sue letture di evasione erano dense di misteri, romanzi gialli e thriller.<br \/>\nQuando arrivava l&#8217;estate, le cose rallentavano. I genitori mandavano i figli in campeggio a luglio, mentre a loro rimanevano la casa e tutta la citt\u00e0 di New York come un enorme parco giochi. Agosto era invece il periodo delle vacanze insieme in famiglia. Noleggiavano un&#8217;auto per un mese e la riempivano di tutto ci\u00f2 che pensavano potesse servirgli in villeggiatura. Guidavano per diverse ore fino a raggiungere una baita tranquilla di alcuni amici e passare l\u00e0 l&#8217;intero mese. <span style=\"color: #3366ff;\"><strong>Prima di partire, il padre di Wally Bock metteva insieme il suo &#8220;piano di lettura&#8221; per l&#8217;estate.<\/strong><\/span> Sapeva che Agosto sarebbe stato pieno di sonnellini e partite a carte, ma sapeva anche che avrebbe letto molto, come aveva sempre fatto. Considerava per\u00f2 l&#8217;estate il momento giusto per leggere qualcosa di diverso.<\/p>\n<p>Preparava cos\u00ec tre liste di titoli, da cui scegliere alla fine solo i migliori, mentre la quarta categoria \u00e8 stata aggiunta direttamente da Wally Bock, perfezionando questo suo metodo:<\/p>\n<ol>\n<li>libri che hai sempre voluto leggere<\/li>\n<li>libri da leggere per divertimento<\/li>\n<li>libri completamente differenti dai tuoi gusti<\/li>\n<li>grandi libri da rileggere<\/li>\n<\/ol>\n<h2><span style=\"color: #3366ff;\">Libri che hai sempre voluto leggere<\/span><\/h2>\n<p>C&#8217;era sempre un libro che il padre di Wally Bock voleva leggere e che non aveva mai letto, mancandone l&#8217;occasione. A volte si trattava di un testo di &#8220;grande riflessione&#8221;. Di solito leggeva cos\u00ec velocemente da &#8220;inalare&#8221; i libri, ma si avvicinava a questi titoli in modo particolare. <span style=\"color: #3366ff;\"><strong>Spesso li leggeva lentamente, una pagina per volta, in modo da avere anche il tempo di riflettere su ci\u00f2 che aveva appena appreso prima di andare avanti.<\/strong><\/span><br \/>\nA volte il libro &#8220;che avrebbe sempre voluto leggere&#8221; era su un argomento che conosceva bene e che desiderava approfondire, un testo di saggistica o una raccolta di sermoni, mentre altre estati leggeva un romanzo particolarmente intrigante, gustandolo con molta calma.<br \/>\nPer le vostre letture estive, scegliete un libro che avete sempre voluto leggere e prendetevi il tempo per leggerlo.<\/p>\n<p>Pensandoci bene, in questa categoria rientra a pieno diritto proprio <em>Guerra e pace<\/em> di Lev Tolstoj. Ho sempre voluto leggerlo, senza alcun dubbio, ma ancora di pi\u00f9 dopo aver assaggiato l&#8217;altro grande romanzo di questo celeberrimo autore, <a href=\"https:\/\/www.webnauta.it\/wordpress\/anna-karenina-lev-tolstoj\/\" target=\"_blank\" rel=\"noopener\"><em>Anna Karenina<\/em><\/a>. E lo sto proprio assaporando lentamente, paragrafo per paragrafo, riempiendo le pagine di post-it colorati nei passaggi pi\u00f9 importanti, quelli che un giorno vorr\u00f2 anche rileggere e riscoprire.<\/p>\n<h2><span style=\"color: #3366ff;\">Libri da leggere per divertimento<\/span><\/h2>\n<p>Leggere per divertimento significa concedersi di affondare gli occhi tra le pagine dei nostri generi letterari preferiti, <span style=\"color: #3366ff;\"><strong>qualcuno la chiama narrativa di consumo<\/strong><\/span>, ma non \u00e8 detto che sia proprio quella la vostra scelta. Per il padre di Wally Bock leggere per divertimento significava spesso <span style=\"color: #3366ff;\"><strong>leggere diversi libri ma dello stesso autore<\/strong><\/span>, magari qualche voluminosa raccolta di romanzi dello stesso scrittore.<br \/>\nScegliere qualcosa di divertente da leggere durante l&#8217;estate, da intervallare ai testi di &#8220;grande riflessione&#8221; della prima categoria, offre un doppio vantaggio: godere appieno delle nostre vacanze con un&#8217;attivit\u00e0 a lungo desiderata, proprio dilettarsi tra quelle pagine, alla caccia dell&#8217;assassino oppure alla ricerca dell&#8217;amore perduto oppure all&#8217;avventura in terre straniere, ma soprattutto offrirci un luogo sicuro nel caso le altre letture non si siano rivelate all&#8217;altezza delle nostre aspettative.<\/p>\n<p>Eh, con questa categoria potrei riempire facilmente lo zaino. Al momento sono indecisa se portare con me <a href=\"https:\/\/www.amazon.it\/via-male-Unindagine-Cormoran-Strike\/dp\/8850259255\" target=\"_blank\" rel=\"noopener\"><em>La via del male<\/em><\/a>, il terzo romanzo delle indagini di <a href=\"https:\/\/www.webnauta.it\/wordpress\/robert-galbraith-strike\/\" target=\"_blank\" rel=\"noopener\"><em>Cormoran Strike<\/em><\/a>, a firma di Robert Galbraith (ovvero la straordinaria penna di J.K.Rowling, l&#8217;autrice di Harry Potter). Me lo sto tenendo da parte da molto tempo, proprio come libro-cioccolatino-coccola e le ferie sarebbero proprio l&#8217;occasione propizia per concederselo.<br \/>\nA tal proposito, lancio anche un appello ai miei lettori: se qualcuno avesse notizia della <a href=\"https:\/\/it.wikipedia.org\/wiki\/Strike_(serie_televisiva)\" target=\"_blank\" rel=\"noopener\"><em>miniserie televisiva Strike<\/em><\/a>, se per caso decidono di passarla in qualche canale italiano in chiaro, per cortesia, fatemi un fischio, scrivetemi un commento, cercatemi sui social per dirmelo. L&#8217;avevo intravvista su Top Crime proprio mentre stavo leggendo il primo romanzo, e poi niente, sembra scomparsa per sempre.<br \/>\nL&#8217;altro romanzo in lizza, consegnato di fresco dal corriere, che mi ha afferrato da subito per l&#8217;immagine di copertina (un obl\u00f2 di una nave che mostra il blu intenso del mare l\u00e0 fuori, quale miglior richiamo per un navigatore?! \ud83d\ude00 ), \u00e8 <a href=\"https:\/\/www.amazon.it\/Tutto-sar%C3%A0-perfetto-Lorenzo-Marone\/dp\/880789470X\" target=\"_blank\" rel=\"noopener\"><em>Tutto sar\u00e0 perfetto<\/em><\/a>\u00a0di Lorenzo Marone, un autore di cui ho sentito parlare benissimo e da tempo voglio scoprire. Anche il titolo \u00e8 uno splendido augurio per la mia vacanza e mi vedo gi\u00e0, seduta sulla sdraio del terrazzo fronte mare, al calar della sera, leggere la storia del protagonista Andrea, quarantenne single, ostinatamente immaturo. Siccome ne conosco uno anch&#8217;io, sorrido all&#8217;idea di trovare qualche punto in comune&#8230; \ud83d\ude09<\/p>\n<h2><span style=\"color: #3366ff;\">Libri completamente differenti dai tuoi gusti<\/span><\/h2>\n<p>In questa categoria ci sono i libri stimolanti, in inglese Wally Bock li chiama &#8220;Pump-Priming Book&#8221;, dove il pump-priming \u00e8 un&#8217;azione intrapresa per stimolare un&#8217;economia e il termine deriva dal funzionamento delle pompe idrauliche pi\u00f9 vecchie, dove una valvola di aspirazione doveva essere adescata con acqua, in modo che la pompa funzionasse correttamente. Questi sono quindi <span style=\"color: #3366ff;\"><strong>libri che dovrebbero darvi una sferzata di novit\u00e0<\/strong><\/span>, qualche nuova idea da conoscere, una materia che non avete mai avvicinato, magari lo studio di una lingua o di un hobby, qualcosa di completamente differente dalle vostre usuali letture.<\/p>\n<p>Il padre di Wally Bock cercava di leggere ogni estate almeno un testo che fosse al di fuori della sua abituale gamma di letture e si lasciava consigliare dalle altre persone, amici o semplici conoscenti, quali grandi libri avessero letto di recente. Un&#8217;estate lesse un libro sull&#8217;architettura delle chiese tedesche del dopoguerra, un altro anno un libro sul pittore Paul Gauguin. Gli argomenti erano i pi\u00f9 disparati, ma l&#8217;unica cosa che avevano in comune era che non erano affatto il genere di libri che leggeva di solito. <span style=\"color: #3366ff;\"><strong>Riteneva che immergersi ogni anno in un testo interessante, fuori dalla propria zona di comfort, aiutasse a rimanere freschi e creativi.<\/strong><\/span> Scegliete quindi un libro su qualcosa di cui non avete mai letto, stimolante per il vostro cervello, ma non noioso, deve soprattutto incuriosirvi.<\/p>\n<p>Per la mia selezione, mi sono lasciata guidare dal marketing, in particolare content marketing e copywriting. Charles Bukowski mi perseguita gi\u00e0 da un po&#8217;, viene spesso citato come un esempio di scrittura asciutta, come ho spiegato in questo post: <a href=\"https:\/\/www.webnauta.it\/wordpress\/editare-ridurre-un-testo\/\" target=\"_blank\" rel=\"noopener\"><em>Come editare e ridurre un testo del 40%<\/em><\/a>\u00a0Cos\u00ec mi sono decisa e ho preso il cartaceo di <em><a href=\"https:\/\/www.amazon.it\/Compagno-sbronze-Charles-Bukowski\/dp\/8807881381\" target=\"_blank\" rel=\"noopener\">Compagno di sbronze<\/a>,<\/em>\u00a0una raccolta di racconti anticonformisti, selvaggi e provocatori, ritenuta una delle sue migliori opere. Quindi il miglior libro per imparare a conoscerlo. L&#8217;ho gi\u00e0 sbirciato qua e l\u00e0, e mi sono ritrovata a sorridere di qualche battuta o piccoli dialoghi. Anche i titoli dei racconti sono tutto un programma. Questo va sicuramente nello zainetto.<\/p>\n<h2><span style=\"color: #3366ff;\">Grandi libri da rileggere<\/span><\/h2>\n<p>Questa \u00e8 la categoria inserita direttamente da Wally Bock nel metodo studiato da suo padre: <span style=\"color: #3366ff;\"><strong>ogni anno rileggere un grande libro del passato.<\/strong><\/span><br \/>\nPenserete subito ai classici, gli intramontabili della letteratura. Ma nella categoria &#8220;grandi libri&#8221; ci sono in realt\u00e0 i vostri grandi libri, <span style=\"color: #3366ff;\"><strong>quelli che hanno segnato la vostra vita, in qualche momento particolare.<\/strong><\/span> Molti sono i motivi per rileggerli: per ritornare alle emozioni della prima lettura (anche se poi non saranno le stesse, perch\u00e9 siete cresciuti, almeno un pochino); per approfondire qualche passaggio che avete letto velocemente o che avete dimenticato nel tempo; per cogliere significati diversi nelle stesse parole, forti dell&#8217;esperienza accumulata; e se siete un autore, per studiare il libro, scomporlo, rielaborarlo, analizzarlo con una rilettura ragionata, da utilizzare poi nella vostra scrittura.<\/p>\n<p>Devo ammettere che a questa quarta possibilit\u00e0 ho arricciato un po&#8217; il naso, proprio come la bionda strega Samantha in <a href=\"https:\/\/it.wikipedia.org\/wiki\/Vita_da_strega\" target=\"_blank\" rel=\"noopener\"><em>Vita da strega<\/em><\/a> quando qualcosa non la convince e vuole rimettere tutto a posto con la magia. Sono pochissimi i libri che a tratti mi viene voglia di rileggere e anche in quel caso non \u00e8 una rilettura completa, ma vado a colpo sicuro su capitoli e paragrafi preferiti, quasi a memoria. Per\u00f2, complice un piccolo libricino giallo regalatomi da Feltrinelli per l&#8217;acquisto di due romanzi in offerta speciale, un volumetto incantevole pieno di citazioni della ineffabile Miss Marple, mi \u00e8 venuta una voglia improvvisa di leggere proprio lei, la mia cara Agatha Christie, la regina incontrastata del giallo. E sarebbe un rileggere, perch\u00e9 durante l&#8217;adolescenza ne ho divorati cos\u00ec tanti di romanzi della Christie, sia con protagonista l&#8217;investigatore Hercule Poirot che l&#8217;acuta zietta Miss Jane Marple. Non ricordo molto delle trame, \u00e8 passato cos\u00ec tanto tempo che sarebbe in realt\u00e0 come leggere per la prima volta. Forse comincer\u00f2 proprio da <a href=\"https:\/\/www.amazon.it\/gp\/product\/8804682876\" target=\"_blank\" rel=\"noopener\"><em>La morte nel villaggio<\/em><\/a>, dove fa per la prima volta la sua comparsa proprio il personaggio di Miss Marple. Per\u00f2 porto con me nello zaino il lettore Kobo e l\u00ec dentro ho la fortuna di avere tutti, ma proprio tutti, i libri di Agatha Christie. \ud83d\ude09<\/p>\n<h2><span style=\"color: #3366ff;\">Cosa leggerete quest&#8217;estate?<\/span><\/h2>\n<p>Anzi, costa state gi\u00e0 leggendo in questa torrida estate? Quali altri titoli avete in programma di leggere fino a settembre? Soprattutto, quali libri vi sentite di consigliare per le diverse categorie?<br \/>\nForza, il passaparola \u00e8 il miglior metodo per scoprire nuove emozionanti letture. \ud83d\ude42<\/p>\n<p>&nbsp;<\/p>\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\" data-instgrm-captioned=\"\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CfEn-7Us26r\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\">\n<div style=\"padding: 16px;\">\n<p>&nbsp;<\/p>\n<div style=\"display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display: block; height: 50px; margin: 0 auto 12px; width: 50px;\"><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\"color: #3897f0; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: 550; line-height: 18px;\">Visualizza questo post su Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #f4f4f4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg);\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\"width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\"background-color: #f4f4f4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\" href=\"https:\/\/www.instagram.com\/p\/CfEn-7Us26r\/?utm_source=ig_embed&amp;utm_campaign=loading\" target=\"_blank\" rel=\"noopener\">Un post condiviso da Barbara Businaro (@barbarawebnauta)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nonostante le temperature torride che gi\u00e0 da due mesi ci affliggono e che di fatto ci hanno catapultato in questa estate infuocata senza nemmeno un briciolo di primavera, ho cominciato a sentire l&#8217;atmosfera estiva solo in questa settimana. Le valigie per le vacanze sono in fase di preparazione, per ora il loro ipotetico contenuto sparso [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27254,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[15,34,17],"class_list":["post-27255","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-solo-un-istante","tag-diario","tag-ispirazioni","tag-libri"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.8 (Yoast SEO v26.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Come si scelgono i libri estivi? - webnauta<\/title>\n<meta name=\"description\" content=\"Come si scelgono i libri estivi? Come decidere quali romanzi mettere in valigia per le nostre vacanze?...webnauta - navigatore in un oceano di parole\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come si scelgono i libri estivi?\" \/>\n<meta property=\"og:description\" content=\"Come si scelgono i libri estivi? Come decidere quali romanzi mettere in valigia per le nostre vacanze?...webnauta - navigatore in un oceano di parole\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/\" \/>\n<meta property=\"og:site_name\" content=\"webnauta\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/barbara.businaro.9\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/barbara.businaro.9\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-30T20:30:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.webnauta.it\/wordpress\/wp-content\/uploads\/2022\/06\/Libri_estivi.png\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Barbara Businaro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@barbarawebnauta\" \/>\n<meta name=\"twitter:site\" content=\"@barbarawebnauta\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Barbara Businaro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/\"},\"author\":{\"name\":\"Barbara Businaro\",\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/#\/schema\/person\/9a1f7a6e3b52bbe5b9d265d2d671d1a1\"},\"headline\":\"Come si scelgono i libri estivi?\",\"datePublished\":\"2022-06-30T20:30:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/\"},\"wordCount\":2775,\"commentCount\":16,\"publisher\":{\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/#\/schema\/person\/9a1f7a6e3b52bbe5b9d265d2d671d1a1\"},\"image\":{\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.webnauta.it\/wordpress\/wp-content\/uploads\/2022\/06\/Libri_estivi.png\",\"keywords\":[\"diario di viaggio\",\"ispirazioni\",\"libri\"],\"articleSection\":[\"Solo un istante\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/\",\"url\":\"https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/\",\"name\":\"Come si scelgono i libri estivi? - webnauta\",\"isPartOf\":{\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.webnauta.it\/wordpress\/wp-content\/uploads\/2022\/06\/Libri_estivi.png\",\"datePublished\":\"2022-06-30T20:30:07+00:00\",\"description\":\"Come si scelgono i libri estivi? Come decidere quali romanzi mettere in valigia per le nostre vacanze?...webnauta - navigatore in un oceano di parole\",\"breadcrumb\":{\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/#primaryimage\",\"url\":\"https:\/\/www.webnauta.it\/wordpress\/wp-content\/uploads\/2022\/06\/Libri_estivi.png\",\"contentUrl\":\"https:\/\/www.webnauta.it\/wordpress\/wp-content\/uploads\/2022\/06\/Libri_estivi.png\",\"width\":650,\"height\":450,\"caption\":\"Come si scelgono i libri estivi? Quattro categorie per aiutarci\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.webnauta.it\/wordpress\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Come si scelgono i libri estivi?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/#website\",\"url\":\"https:\/\/www.webnauta.it\/wordpress\/\",\"name\":\"webnauta\",\"description\":\"navigatore in un oceano di parole\",\"publisher\":{\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/#\/schema\/person\/9a1f7a6e3b52bbe5b9d265d2d671d1a1\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.webnauta.it\/wordpress\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/#\/schema\/person\/9a1f7a6e3b52bbe5b9d265d2d671d1a1\",\"name\":\"Barbara Businaro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.webnauta.it\/wordpress\/wp-content\/uploads\/2020\/02\/BarbaraBusinaro2020_rounded.png\",\"contentUrl\":\"https:\/\/www.webnauta.it\/wordpress\/wp-content\/uploads\/2020\/02\/BarbaraBusinaro2020_rounded.png\",\"width\":500,\"height\":512,\"caption\":\"Barbara Businaro\"},\"logo\":{\"@id\":\"https:\/\/www.webnauta.it\/wordpress\/#\/schema\/person\/image\/\"},\"description\":\"webnauta.it \u2022 Blog personale di Barbara Businaro \u2022 Scrivo, tra una tempesta e l''altra. Chiunque pu\u00f2 tenere il timone quando il mare \u00e8 calmo.\",\"sameAs\":[\"http:\/\/www.webnauta.it\",\"http:\/\/www.facebook.com\/barbara.businaro.9\",\"https:\/\/www.instagram.com\/barbarawebnauta\/\",\"https:\/\/x.com\/barbarawebnauta\"],\"url\":\"https:\/\/www.webnauta.it\/wordpress\/author\/maxadmin\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Come si scelgono i libri estivi? - webnauta","description":"Come si scelgono i libri estivi? Come decidere quali romanzi mettere in valigia per le nostre vacanze?...webnauta - navigatore in un oceano di parole","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/","og_locale":"it_IT","og_type":"article","og_title":"Come si scelgono i libri estivi?","og_description":"Come si scelgono i libri estivi? Come decidere quali romanzi mettere in valigia per le nostre vacanze?...webnauta - navigatore in un oceano di parole","og_url":"https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/","og_site_name":"webnauta","article_publisher":"http:\/\/www.facebook.com\/barbara.businaro.9","article_author":"http:\/\/www.facebook.com\/barbara.businaro.9","article_published_time":"2022-06-30T20:30:07+00:00","og_image":[{"width":650,"height":450,"url":"https:\/\/www.webnauta.it\/wordpress\/wp-content\/uploads\/2022\/06\/Libri_estivi.png","type":"image\/png"}],"author":"Barbara Businaro","twitter_card":"summary_large_image","twitter_creator":"@barbarawebnauta","twitter_site":"@barbarawebnauta","twitter_misc":{"Scritto da":"Barbara Businaro","Tempo di lettura stimato":"15 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/#article","isPartOf":{"@id":"https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/"},"author":{"name":"Barbara Businaro","@id":"https:\/\/www.webnauta.it\/wordpress\/#\/schema\/person\/9a1f7a6e3b52bbe5b9d265d2d671d1a1"},"headline":"Come si scelgono i libri estivi?","datePublished":"2022-06-30T20:30:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/"},"wordCount":2775,"commentCount":16,"publisher":{"@id":"https:\/\/www.webnauta.it\/wordpress\/#\/schema\/person\/9a1f7a6e3b52bbe5b9d265d2d671d1a1"},"image":{"@id":"https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webnauta.it\/wordpress\/wp-content\/uploads\/2022\/06\/Libri_estivi.png","keywords":["diario di viaggio","ispirazioni","libri"],"articleSection":["Solo un istante"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/","url":"https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/","name":"Come si scelgono i libri estivi? - webnauta","isPartOf":{"@id":"https:\/\/www.webnauta.it\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/#primaryimage"},"image":{"@id":"https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webnauta.it\/wordpress\/wp-content\/uploads\/2022\/06\/Libri_estivi.png","datePublished":"2022-06-30T20:30:07+00:00","description":"Come si scelgono i libri estivi? Come decidere quali romanzi mettere in valigia per le nostre vacanze?...webnauta - navigatore in un oceano di parole","breadcrumb":{"@id":"https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/#primaryimage","url":"https:\/\/www.webnauta.it\/wordpress\/wp-content\/uploads\/2022\/06\/Libri_estivi.png","contentUrl":"https:\/\/www.webnauta.it\/wordpress\/wp-content\/uploads\/2022\/06\/Libri_estivi.png","width":650,"height":450,"caption":"Come si scelgono i libri estivi? Quattro categorie per aiutarci"},{"@type":"BreadcrumbList","@id":"https:\/\/www.webnauta.it\/wordpress\/come-si-scelgono-i-libri-estivi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.webnauta.it\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Come si scelgono i libri estivi?"}]},{"@type":"WebSite","@id":"https:\/\/www.webnauta.it\/wordpress\/#website","url":"https:\/\/www.webnauta.it\/wordpress\/","name":"webnauta","description":"navigatore in un oceano di parole","publisher":{"@id":"https:\/\/www.webnauta.it\/wordpress\/#\/schema\/person\/9a1f7a6e3b52bbe5b9d265d2d671d1a1"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.webnauta.it\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Person","Organization"],"@id":"https:\/\/www.webnauta.it\/wordpress\/#\/schema\/person\/9a1f7a6e3b52bbe5b9d265d2d671d1a1","name":"Barbara Businaro","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.webnauta.it\/wordpress\/#\/schema\/person\/image\/","url":"https:\/\/www.webnauta.it\/wordpress\/wp-content\/uploads\/2020\/02\/BarbaraBusinaro2020_rounded.png","contentUrl":"https:\/\/www.webnauta.it\/wordpress\/wp-content\/uploads\/2020\/02\/BarbaraBusinaro2020_rounded.png","width":500,"height":512,"caption":"Barbara Businaro"},"logo":{"@id":"https:\/\/www.webnauta.it\/wordpress\/#\/schema\/person\/image\/"},"description":"webnauta.it \u2022 Blog personale di Barbara Businaro \u2022 Scrivo, tra una tempesta e l''altra. Chiunque pu\u00f2 tenere il timone quando il mare \u00e8 calmo.","sameAs":["http:\/\/www.webnauta.it","http:\/\/www.facebook.com\/barbara.businaro.9","https:\/\/www.instagram.com\/barbarawebnauta\/","https:\/\/x.com\/barbarawebnauta"],"url":"https:\/\/www.webnauta.it\/wordpress\/author\/maxadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.webnauta.it\/wordpress\/wp-json\/wp\/v2\/posts\/27255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.webnauta.it\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.webnauta.it\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.webnauta.it\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.webnauta.it\/wordpress\/wp-json\/wp\/v2\/comments?post=27255"}],"version-history":[{"count":2,"href":"https:\/\/www.webnauta.it\/wordpress\/wp-json\/wp\/v2\/posts\/27255\/revisions"}],"predecessor-version":[{"id":27257,"href":"https:\/\/www.webnauta.it\/wordpress\/wp-json\/wp\/v2\/posts\/27255\/revisions\/27257"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.webnauta.it\/wordpress\/wp-json\/wp\/v2\/media\/27254"}],"wp:attachment":[{"href":"https:\/\/www.webnauta.it\/wordpress\/wp-json\/wp\/v2\/media?parent=27255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.webnauta.it\/wordpress\/wp-json\/wp\/v2\/categories?post=27255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.webnauta.it\/wordpress\/wp-json\/wp\/v2\/tags?post=27255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}